{"id":3129,"date":"2017-05-18T10:38:24","date_gmt":"2017-05-18T08:38:24","guid":{"rendered":"https:\/\/www.kenial.de\/de\/?page_id=3129"},"modified":"2025-12-07T12:54:54","modified_gmt":"2025-12-07T11:54:54","slug":"nepal-2016","status":"publish","type":"page","link":"https:\/\/www.kenial.de\/de\/kenial\/nepal\/nepal-2016\/","title":{"rendered":"Nepal 2016"},"content":{"rendered":"Nepal 2016 \u2022 <a href=\"https:\/\/www.kenial.de\/de\/kenial\/nepal\/nepal-2017\/\">Nepal 2017<\/a> \u2022 <a href=\"https:\/\/www.kenial.de\/de\/kenial\/nepal\/nepal-2017-expedition\/\">Nepal 2017 Exped<\/a> \u2022 <a href=\"https:\/\/www.kenial.de\/de\/kenial\/nepal\/nepal-2018\/\">Nepal 2018<\/a> \u2022 <a href=\"https:\/\/www.kenial.de\/de\/kenial\/nepal\/nepal-2019\/\">Nepal 2019<\/a> \u2022 <a href=\"https:\/\/www.kenial.de\/de\/kenial\/nepal\/nepal-2021\/\">Nepal 2021<\/a> \u2022 <a href=\"https:\/\/www.kenial.de\/de\/kenial\/nepal\/nepal-2022\/\">Nepal 2022<\/a><\/p>\n<p>Der keniale Bergsteiger Luis\u00a0Stitzinger bricht im Oktober\u00a02016 auf zum Rolwaling-Trekking und zuvor brachte er den Waisenkindern genau\u00a0das, was sie brauchen: Warme Jacken und Schuhe f\u00fcr\u00a0Bidesh, Kamal, Maya, Sita&#8230; finanziert durch eure\u00a0<a href=\"https:\/\/www.kenial.de\/mitmachen\/\">Spenden<\/a>. Die Schuhe wurden komplett von LOWA gesponsort. In den richtigen Gr\u00f6\u00dfen. Alles ganz gezielt und direkt. Gro\u00dfartig.<br \/>\n<div class=\"oneThird\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3190 size-full\" src=\"https:\/\/www.kenial.de\/wp-content\/uploads\/2017\/05\/lowa_nepal_kl.jpg\" alt=\"\" width=\"200\" height=\"147\" \/><br \/>\nKids. Jetzt hei\u00dft es erst einmal Schuhe binden \u00fcben&#8230; ein riesen Gewimmel und freudiges Probieren. Danke an LOWA.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"oneThird\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1382 size-full\" src=\"https:\/\/www.kenial.de\/wp-content\/uploads\/2016\/02\/manaslu_kl.jpg\" alt=\"\" width=\"200\" height=\"147\" \/><br \/>\nBerg. Der Mount Manaslu (8163m) ist der acht h\u00f6chste Berg der Welt. Alix von Melle und Luis Stitzinger werden diesen Berg sicher noch angehen. Und wir dr\u00fccken die Daumen.<\/p>\n<\/div>\n<div class=\"oneThird last\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1375 size-full\" src=\"https:\/\/www.kenial.de\/wp-content\/uploads\/2016\/02\/al_lu.jpg\" alt=\"\" width=\"200\" height=\"147\" \/><br \/>\nAthleten. Alix von Melle und Luis Stizinger sind das erfolgreichste Expeditions und Bergsteigerpaar. Bis jetzt konnten sie zusammen sechs der 8000er ohne k\u00fcnstlichen Sauerstoff besteigen.<br \/>\n<a href=\"https:\/\/www.kenial.de\/nepal-athleten\/\">read more<\/a><\/p>\n<\/div><div class=\"clear\"><\/div>\n<div class=\"theParallaxCrestaBlock\"><div class=\"theParallaxCresta fortunato-short-parallax-617\" style=\"background-image: url(https:\/\/www.kenial.de\/wp-content\/uploads\/2016\/02\/stupa.jpg); height:600px;\"><h2><\/h2><\/div><\/div><script type=\"text\/javascript\">(function($) { $(document).ready(function() { if ( \/Android|webOS|iPhone|iPad|iPod|BlackBerry|IEMobile|Opera Mini\/i.test(navigator.userAgent) ) {} else { $(\".fortunato-short-parallax-617\").scrollparallax(\"50%\", \"0.2\"); } }); })(jQuery);<\/script>","protected":false},"excerpt":{"rendered":"<p>Nepal 2016 \u2022 Nepal 2017 \u2022 Nepal 2017 Exped \u2022 Nepal 2018 \u2022 Nepal 2019 \u2022 Nepal 2021 \u2022 Nepal 2022 Der keniale Bergsteiger Luis\u00a0Stitzinger bricht im Oktober\u00a02016 auf zum Rolwaling-Trekking und zuvor brachte er den Waisenkindern genau\u00a0das, was sie brauchen: Warme Jacken und Schuhe f\u00fcr\u00a0Bidesh, Kamal, Maya, Sita&#8230; finanziert durch eure\u00a0Spenden. Die Schuhe wurden&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2270,"parent":1381,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3129","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/pages\/3129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/comments?post=3129"}],"version-history":[{"count":3,"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/pages\/3129\/revisions"}],"predecessor-version":[{"id":10394,"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/pages\/3129\/revisions\/10394"}],"up":[{"embeddable":true,"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/pages\/1381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/media\/2270"}],"wp:attachment":[{"href":"https:\/\/www.kenial.de\/de\/wp-json\/wp\/v2\/media?parent=3129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}